{"id":758,"date":"2016-11-08T17:00:36","date_gmt":"2016-11-08T15:00:36","guid":{"rendered":"https:\/\/academysantaclaus.com\/zh-hans\/?page_id=758"},"modified":"2018-08-13T19:26:08","modified_gmt":"2018-08-13T17:26:08","slug":"yin-si-zheng-ce","status":"publish","type":"page","link":"https:\/\/academysantaclaus.com\/zh-hans\/yin-si-zheng-ce\/","title":{"rendered":"\u9690\u79c1\u653f\u7b56 &#8211; Sus datos seguros"},"content":{"rendered":"<div style=\"margin: 0px 35px 0px 35px;\">\n<h1>Pol\u00edtica de privacidad &#8211; Sus datos seguros<\/h1>\n<h2>Informaci\u00f3n en cumplimiento de la normativa de protecci\u00f3n de datos personales<\/h2>\n<p>En Europa y en Espa\u00f1a existen normas de protecci\u00f3n de datos pensadas para proteger su informaci\u00f3n personal de obligado cumplimiento para nuestra entidad.<\/p>\n<p>Por ello, es muy importante para nosotros que entienda perfectamente qu\u00e9 vamos a hacer con los datos personales que le pedimos.<\/p>\n<p>As\u00ed, seremos transparentes y le daremos el control de sus datos, con un lenguaje sencillo y opciones claras que le permitir\u00e1n decidir qu\u00e9 haremos con su informaci\u00f3n personal.<\/p>\n<p>Por favor, si una vez le\u00edda la presente informaci\u00f3n le queda alguna duda, no dude en preguntarnos.<\/p>\n<p>Muchas gracias por su colaboraci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>\u00bf<\/strong><strong>Qui\u00e9nes somos?<\/strong><\/li>\n<li>Nuestra denominaci\u00f3n: <strong>ACADEMIA SANTA CLAUS S.A.<\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Nuestro CIF \/ NIF: <strong>A08991085<\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Nuestra actividad principal:<strong> Ense\u00f1anza infantil y primaria<\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Nuestra direcci\u00f3n: <strong>C\/ Lle\u00f3 XIII, 12, CP 08022, BARCELONA (Barcelona)<\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Nuestro tel\u00e9fono de contacto: <strong>934171847<\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Nuestra direcci\u00f3n de correo electr\u00f3nico de contacto: : <strong>mail@academysantaclaus.com<\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Nuestra p\u00e1gina web: <strong>academysantaclaus.com<\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>Para su confianza y seguridad, le informamos que somos una entidad inscrita en el siguiente Registro Mercantil \/Registro P\u00fablico:<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Estamos a su disposici\u00f3n, no dude en contactar con nosotros.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>\u00bfPara qu\u00e9 vamos a usar sus datos?<\/strong><\/li>\n<\/ul>\n<p>Con car\u00e1cter general, sus datos personales ser\u00e1n usados para poder relacionarnos con usted y poder prestarle nuestros servicios.<\/p>\n<p>Asimismo, tambi\u00e9n pueden ser usados para otras actividades, como enviarle publicidad o promocionar nuestras actividades.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>\u00bfPor qu\u00e9 necesitamos usar sus datos?<\/strong><\/li>\n<\/ul>\n<p>Sus datos personales son necesarios para poder relacionarnos con usted y poder prestarle nuestros servicios. En este sentido, pondremos a su disposici\u00f3n una serie de casillas que le permitir\u00e1n decidir de manera clara y sencilla sobre el uso de su informaci\u00f3n personal.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>\u00bfQui\u00e9n va a conocer la informaci\u00f3n que le pedimos?<\/strong><\/li>\n<\/ul>\n<p>Con car\u00e1cter general, s\u00f3lo el personal de nuestra entidad que est\u00e9 debidamente autorizado podr\u00e1 tener conocimiento de la informaci\u00f3n que le pedimos.<\/p>\n<p>De igual modo, podr\u00e1n tener conocimiento de su informaci\u00f3n personal aquellas entidades que necesiten tener acceso a la misma para que podamos prestarle nuestros servicios. As\u00ed por ejemplo, nuestro banco conocer\u00e1 sus datos si el pago de nuestros servicios se realiza mediante tarjeta o transferencia bancaria.<\/p>\n<p>Asimismo, tendr\u00e1n conocimiento de su informaci\u00f3n aquellas entidades p\u00fablicas o privadas a las cuales estemos obligados a facilitar sus datos personales con motivo del cumplimiento de alguna ley. Poni\u00e9ndole un ejemplo, la Ley Tributaria obliga a facilitar a la Agencia Tributaria determinada informaci\u00f3n sobre operaciones econ\u00f3micas que superen una determinada cantidad.<\/p>\n<p>En el caso de que, al margen de los supuestos comentados, necesitemos dar a conocer\u00a0 su informaci\u00f3n personal a otras entidades, le solicitaremos previamente su permiso a trav\u00e9s de opciones claras que le permitir\u00e1n decidir a este respecto.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>\u00bfC\u00f3mo vamos a proteger sus datos?<\/strong><\/li>\n<\/ul>\n<p>Protegeremos sus datos con medidas de seguridad eficaces en funci\u00f3n de los riesgos que conlleve el uso de su informaci\u00f3n.<\/p>\n<p>Para ello, nuestra entidad ha aprobado una Pol\u00edtica de Protecci\u00f3n de Datos y se realizan controles y auditor\u00edas anuales para verificar que sus datos personales est\u00e1n seguros en todo momento.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>\u00bfEnviaremos sus datos a otros pa\u00edses?<\/strong><\/li>\n<\/ul>\n<p>En el mundo hay pa\u00edses que son seguros para sus datos y otros que no lo son tanto. As\u00ed por ejemplo, la Uni\u00f3n Europea es un entorno seguro para sus datos. Nuestra pol\u00edtica es no enviar su informaci\u00f3n personal a ning\u00fan pa\u00eds que no sea seguro desde el punto de vista de la protecci\u00f3n de sus datos.<\/p>\n<p>En el caso de que, con motivo de prestarle el servicio, sea imprescindible enviar sus datos a un pa\u00eds que no sea tan seguro como Espa\u00f1a, siempre le solicitaremos previamente su permiso y aplicaremos medidas de seguridad eficaces que reduzcan los riesgos del env\u00edo de su informaci\u00f3n personal a otro pa\u00eds.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>\u00bfDurante cu\u00e1nto tiempo vamos a conservar sus datos?<\/strong><\/li>\n<\/ul>\n<p>Conservaremos sus datos durante nuestra relaci\u00f3n y mientras nos obliguen las leyes. Una vez finalizados los plazos legales aplicables, procederemos a eliminarlos de forma segura y respetuosa con el medio ambiente.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>\u00bfCu\u00e1les son sus derechos de protecci\u00f3n de datos?<\/strong><\/li>\n<\/ul>\n<p>En cualquier momento puede dirigirse a nosotros para saber qu\u00e9 informaci\u00f3n tenemos sobre usted, rectificarla si fuese incorrecta y eliminarla una vez finalizada nuestra relaci\u00f3n, en el caso de que ello sea legalmente posible.<\/p>\n<p>Tambi\u00e9n tiene derecho a solicitar el traspaso de su informaci\u00f3n a otra entidad. Este derecho se llama \u201cportabilidad\u201d y puede ser \u00fatil en determinadas situaciones.<\/p>\n<p>Para solicitar alguno de estos derechos, deber\u00e1 realizar una solicitud escrita a nuestra direcci\u00f3n, junto con una fotocopia de su DNI, para poder identificarle.<\/p>\n<p>En las oficinas de nuestra entidad disponemos de formularios espec\u00edficos para solicitar dichos derechos y le ofrecemos nuestra ayuda para su cumplimentaci\u00f3n.<\/p>\n<p>Para saber m\u00e1s sobre sus derechos de protecci\u00f3n de datos, puede consultar la \u00a0p\u00e1gina web de la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos (<a href=\"http:\/\/www.agpd.es\">www.agpd.es<\/a>).<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>\u00bfPuede retirar su consentimiento si cambia de opini\u00f3n en un momento posterior?<\/strong><\/li>\n<\/ul>\n<p>Usted puede retirar su consentimiento si cambia de opini\u00f3n sobre el uso de sus datos en cualquier momento.<\/p>\n<p>As\u00ed por ejemplo, si usted en su d\u00eda estuvo interesado\/a en recibir publicidad de nuestros productos o servicios, pero ya no desea recibir m\u00e1s publicidad, puede hac\u00e9rnoslo constar a trav\u00e9s del formulario de oposici\u00f3n al tratmiento disponible en las oficinas de nuestra entidad.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>En caso de que entienda que sus derechos han sido desatendidos, \u00bfd\u00f3nde puede formular una reclamaci\u00f3n?<\/strong><\/li>\n<\/ul>\n<p>En caso de que entienda que sus derechos han sido desatendidos por nuestra entidad, puede formular una reclamaci\u00f3n en la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos, a trav\u00e9s de alguno de los medios siguientes:<\/p>\n<ul>\n<li>Sede electr\u00f3nica: www.agpd.es<\/li>\n<li>Direcci\u00f3n postal:<\/li>\n<\/ul>\n<p>Agencia Espa\u00f1ola de Protecci\u00f3n de Datos<br \/>\nC\/ Jorge Juan, 6<br \/>\n28001-Madrid<\/p>\n<ul>\n<li>V\u00eda telef\u00f3nica:<\/li>\n<\/ul>\n<p>Telf. 901 100 099<\/p>\n<p>Telf. 91 266 35 17<\/p>\n<p>Formular una reclamaci\u00f3n en la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos no conlleva ning\u00fan coste y no es necesaria la asistencia de abogado ni procurador.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>\u00bfElaboraremos perfiles sobre usted?<\/strong><\/li>\n<\/ul>\n<p>Nuestra pol\u00edtica es no elaborar perfiles sobre los usuarios de nuestros servicios.<\/p>\n<p>No obstante, pueden existir situaciones en las que, con fines de prestaci\u00f3n del servicio, comerciales o de otro tipo, necesitemos elaborar perfiles de informaci\u00f3n sobre usted. Un ejemplo pudiera ser la utilizaci\u00f3n de su historial de compras o servicios para poder ofrecerle productos o servicios adaptados a sus gustos o necesidades.<\/p>\n<p>En tal caso, aplicaremos medidas de seguridad eficaces que protejan su informaci\u00f3n en todo momento de personas no autorizadas que pretendan utilizarla en su propio beneficio.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<ul>\n<li><strong>\u00bfUsaremos sus datos para otros fines?<\/strong><\/li>\n<\/ul>\n<p>Nuestra pol\u00edtica es no usar sus datos para otras finalidades distintas a las que le hemos explicado. Si, no obstante, necesit\u00e1semos usar sus datos para actividades distintas, siempre le solicitaremos previamente su permiso a trav\u00e9s de opciones claras que le permitir\u00e1n decidir al respecto.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Pol\u00edtica de privacidad &#8211; Sus datos seguros Inform [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":980,"comment_status":"closed","ping_status":"open","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/academysantaclaus.com\/zh-hans\/wp-json\/wp\/v2\/pages\/758"}],"collection":[{"href":"https:\/\/academysantaclaus.com\/zh-hans\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/academysantaclaus.com\/zh-hans\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/academysantaclaus.com\/zh-hans\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/academysantaclaus.com\/zh-hans\/wp-json\/wp\/v2\/comments?post=758"}],"version-history":[{"count":4,"href":"https:\/\/academysantaclaus.com\/zh-hans\/wp-json\/wp\/v2\/pages\/758\/revisions"}],"predecessor-version":[{"id":6625,"href":"https:\/\/academysantaclaus.com\/zh-hans\/wp-json\/wp\/v2\/pages\/758\/revisions\/6625"}],"wp:attachment":[{"href":"https:\/\/academysantaclaus.com\/zh-hans\/wp-json\/wp\/v2\/media?parent=758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}